{"id":13137,"date":"2026-08-24T10:52:06","date_gmt":"2026-08-24T08:52:06","guid":{"rendered":"https:\/\/b-ltravel.com\/?page_id=13137"},"modified":"2026-09-01T10:37:20","modified_gmt":"2026-09-01T08:37:20","slug":"home-dev","status":"publish","type":"page","link":"https:\/\/b-ltravel.com\/en\/home-dev\/","title":{"rendered":"Home-dev"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"13137\" class=\"elementor elementor-13137\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e970b42 elementor-section-stretched Quisommesnous elementor-section-full_width elementor-section-height-full elementor-section-height-default elementor-section-items-middle wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"e970b42\" data-element_type=\"section\" id=\"Quisommesnous\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/b-ltravel.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/AQOMRD0QJNUea-elvmC0LsfYkPq0XjwXmzXVJhAArPreETEvwM3uGHxWIXsZ2chnZ2Jr2r-vAyNU_ITVDpQGA65z.mp4&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-background-video-container elementor-hidden-mobile\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<video class=\"elementor-background-video-hosted\" autoplay muted playsinline loop><\/video>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-685ebcc\" data-id=\"685ebcc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-061a0a5 elementor-widget elementor-widget-heading\" data-id=\"061a0a5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Business &amp; Leisure Travel<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-595185b elementor-widget elementor-widget-heading\" data-id=\"595185b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Votre partenaire d\u2019excellence pour des exp\u00e9riences professionnelles et\nvoyages d\u2019exception.<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3efd3ad e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"3efd3ad\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0fd2c30 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"0fd2c30\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper icon_align_\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"\/en\/nos-services\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">D\u00e9couvrir nos services\/<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9145736 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"9145736\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper icon_align_\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"\/en\/#NousContacter\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Demande un devis<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-920036a elementor-section-full_width elementor-section-stretched classe1 elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"920036a\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a7cce3b\" data-id=\"a7cce3b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-bf4f191 elementor-section-full_width classe1 elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"bf4f191\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1d6a63c\" data-id=\"1d6a63c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e5f75a e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"1e5f75a\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t<div class=\"elementor-element elementor-element-0ba428b e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"0ba428b\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd5e618 elementor-widget elementor-widget-heading\" data-id=\"bd5e618\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Expertise &amp; confiance<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9feb4c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c9feb4c\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cfc4d52 elementor-widget elementor-widget-heading\" data-id=\"cfc4d52\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Plus de 13 ans d\u2019exp\u00e9rience au service de voyages fiables et ma\u00eetris\u00e9s.<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9f0399b e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"9f0399b\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ff76e13 elementor-widget elementor-widget-heading\" data-id=\"ff76e13\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Excellence certifi\u00e9e IATA<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88262d5 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"88262d5\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e62f84c elementor-widget elementor-widget-heading\" data-id=\"e62f84c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Une garantie de s\u00e9curit\u00e9, de conformit\u00e9 et de standards internationaux \u00e9lev\u00e9s.<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2dbd7be e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"2dbd7be\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-26d0913 elementor-widget elementor-widget-heading\" data-id=\"26d0913\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Assistance continue 7j\/7<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69673ae elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"69673ae\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8d770f elementor-widget elementor-widget-heading\" data-id=\"d8d770f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Un accompagnement permanent pour une tranquillit\u00e9 totale \u00e0 chaque \u00e9tape.<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fb2ef7e e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"fb2ef7e\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a388824 elementor-widget elementor-widget-heading\" data-id=\"a388824\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">R\u00e9seau international premium<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2f1eee elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a2f1eee\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5539c45 elementor-widget elementor-widget-heading\" data-id=\"5539c45\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Des partenaires s\u00e9lectionn\u00e9s dans le monde entier pour des exp\u00e9riences sur mesure.<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9e3f9b7 elementor-section-full_width elementor-section-stretched classe1 elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"9e3f9b7\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4116723\" data-id=\"4116723\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6de15e1 elementor-section-full_width classe1 elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6de15e1\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-13e9314\" data-id=\"13e9314\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b051b5f e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"b051b5f\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t<div class=\"elementor-element elementor-element-a9d245e e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"a9d245e\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6270220 elementor-widget elementor-widget-heading\" data-id=\"6270220\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">blt votre partenaire de succ\u00e8s<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dde03cf elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"dde03cf\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3447b9e elementor-widget elementor-widget-heading\" data-id=\"3447b9e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Fond\u00e9e en 2013, BLT est une agence de voyages  \u00e9v\u00e9nementielle de cat\u00e9gorie A.\nNous proposons des prestations sur mesure : d\u00e9placements professionnels, voyages individuels, s\u00e9minaires, congr\u00e8s, team buildings, etc.<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fea5148 e-con-full e-grid wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"fea5148\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6b72342 elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"6b72342\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"1438\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-2-1.jpg\" class=\"attachment-full size-full wp-image-17253\" alt=\"Content 2 1\"  title=\"Les tendances du tourisme corporate en 2026\" srcset=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-2-1.jpg 1920w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-2-1-300x225.jpg 300w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-2-1-1024x767.jpg 1024w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-2-1-768x575.jpg 768w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-2-1-1536x1150.jpg 1536w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-2-1-16x12.jpg 16w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-2-1-900x674.jpg 900w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-2-1-600x449.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Organisation d\u2019\u00e9v\u00e9nements &amp; MICE<\/h3><p class=\"elementor-image-box-description\">Conception et gestion compl\u00e8te de vos \u00e9v\u00e9nements professionnels : s\u00e9minaires, congr\u00e8s,\nconf\u00e9rences et programmes incentive. Une prise en charge globale pens\u00e9e pour garantir\nimpact, fluidit\u00e9 et excellence op\u00e9rationnelle. CTA : Concevoir mon \u00e9v\u00e9nement sur mesure<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-304a96e elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"304a96e\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-3-1.jpg\" class=\"attachment-full size-full wp-image-17254\" alt=\"Content 3 1\"  title=\"Les tendances du tourisme corporate en 2026\" srcset=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-3-1.jpg 1920w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-3-1-300x225.jpg 300w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-3-1-1024x768.jpg 1024w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-3-1-768x576.jpg 768w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-3-1-1536x1152.jpg 1536w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-3-1-16x12.jpg 16w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-3-1-900x675.jpg 900w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-3-1-600x450.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Solutions techniques &amp; interpr\u00e9tariat<\/h3><p class=\"elementor-image-box-description\">Mise \u00e0 disposition de mat\u00e9riel audiovisuel de pointe et services d\u2019interpr\u00e9tariat\nprofessionnels. Une expertise technique qui assure une communication fluide et une\nex\u00e9cution sans faille de vos \u00e9v\u00e9nements internationaux. CTA : Garantir une ex\u00e9cution\nparfaite<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91af4ae elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"91af4ae\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-5-1.jpg\" class=\"attachment-full size-full wp-image-17256\" alt=\"Content 5 1\"  title=\"Les tendances du tourisme corporate en 2026\" srcset=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-5-1.jpg 1920w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-5-1-300x225.jpg 300w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-5-1-1024x768.jpg 1024w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-5-1-768x576.jpg 768w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-5-1-1536x1152.jpg 1536w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-5-1-16x12.jpg 16w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-5-1-900x675.jpg 900w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-5-1-600x450.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Team Building &amp; exp\u00e9riences d\u2019\u00e9quipe<\/h3><p class=\"elementor-image-box-description\">Cr\u00e9ation d\u2019exp\u00e9riences sur mesure pour renforcer la coh\u00e9sion et la performance des\n\u00e9quipes. Des activit\u00e9s innovantes, adapt\u00e9es \u00e0 vos objectifs RH et \u00e0 votre culture\nd\u2019entreprise. CTA : Cr\u00e9er une exp\u00e9rience d\u2019\u00e9quipe<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d5fd73 elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"3d5fd73\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-1-1.jpg\" class=\"attachment-full size-full wp-image-17252\" alt=\"Content 1 1\"  title=\"Les tendances du tourisme corporate en 2026\" srcset=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-1-1.jpg 1920w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-1-1-300x225.jpg 300w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-1-1-1024x768.jpg 1024w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-1-1-768x576.jpg 768w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-1-1-1536x1152.jpg 1536w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-1-1-16x12.jpg 16w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-1-1-900x675.jpg 900w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-1-1-600x450.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Voyage d\u2019affaires &amp; gestion des d\u00e9placements<\/h3><p class=\"elementor-image-box-description\">Gestion compl\u00e8te des voyages professionnels : planification, optimisation des co\u00fbts et\nassistance continue. Une solution pens\u00e9e pour la productivit\u00e9, la flexibilit\u00e9 et la\ntranquillit\u00e9 des voyageurs. CTA : Optimiser mes d\u00e9placements<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-429abf8 elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"429abf8\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-5-1.jpg\" class=\"attachment-full size-full wp-image-17256\" alt=\"Content 5 1\"  title=\"Les tendances du tourisme corporate en 2026\" srcset=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-5-1.jpg 1920w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-5-1-300x225.jpg 300w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-5-1-1024x768.jpg 1024w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-5-1-768x576.jpg 768w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-5-1-1536x1152.jpg 1536w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-5-1-16x12.jpg 16w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-5-1-900x675.jpg 900w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-5-1-600x450.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Billetterie &amp; mobilit\u00e9 internationale<\/h3><p class=\"elementor-image-box-description\">R\u00e9servation et \u00e9mission de billets d\u2019avion avec acc\u00e8s aux meilleures options et tarifs. Une\ngestion rapide et optimis\u00e9e pour tous vos d\u00e9placements nationaux et internationaux. CTA\n: Trouver mon meilleur itin\u00e9raire<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a40bf2e elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"a40bf2e\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-1-1.jpg\" class=\"attachment-full size-full wp-image-17252\" alt=\"Content 1 1\"  title=\"Les tendances du tourisme corporate en 2026\" srcset=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-1-1.jpg 1920w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-1-1-300x225.jpg 300w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-1-1-1024x768.jpg 1024w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-1-1-768x576.jpg 768w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-1-1-1536x1152.jpg 1536w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-1-1-16x12.jpg 16w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-1-1-900x675.jpg 900w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-1-1-600x450.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">H\u00e9bergement &amp; transferts premium<\/h3><p class=\"elementor-image-box-description\">S\u00e9lection et r\u00e9servation d\u2019h\u00f4tels en Tunisie et \u00e0 l\u2019\u00e9tranger, accompagn\u00e9e de services de\ntransport et transferts priv\u00e9s. Une exp\u00e9rience de mobilit\u00e9 fluide, confortable et hautement\nfiable. CTA : R\u00e9server une exp\u00e9rience fluide<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ea2f9d4 elementor-section-full_width elementor-section-stretched classe1 elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"ea2f9d4\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-afbdb71\" data-id=\"afbdb71\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5fa9106 elementor-section-full_width classe1 elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"5fa9106\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e75a4a0 elementor-invisible\" data-id=\"e75a4a0\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4618d0e elementor-widget elementor-widget-text-editor\" data-id=\"4618d0e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong style=\"color: #ef832b;\">BLT Travel,<\/strong><span style=\"font-weight: 400;\">\u00a0fond\u00e9e en 2013, est une agence de voyage premium sp\u00e9cialis\u00e9e dans les voyages d\u2019affaires et de loisirs sur mesure. Affili\u00e9e \u00e0 la FTAV et agr\u00e9\u00e9e IATA, l\u2019agence accompagne ses clients avec excellence, discr\u00e9tion et professionnalisme afin d\u2019offrir des exp\u00e9riences de voyage fluides, \u00e9l\u00e9gantes et parfaitement organis\u00e9es&#8230;<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5dc85d0 elementor-widget elementor-widget-spacer\" data-id=\"5dc85d0\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-adc5aeb elementor-align-center elementor-widget elementor-widget-button\" data-id=\"adc5aeb\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper icon_align_\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"\/en\/qui-sommes-nous\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d2a29a9 elementor-invisible\" data-id=\"d2a29a9\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c8c7251 elementor-widget elementor-widget-image\" data-id=\"c8c7251\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-6-1.jpg\" class=\"attachment-full size-full wp-image-17257\" alt=\"Content 6 1\" srcset=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-6-1.jpg 1920w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-6-1-300x225.jpg 300w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-6-1-1024x768.jpg 1024w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-6-1-768x576.jpg 768w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-6-1-1536x1152.jpg 1536w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-6-1-16x12.jpg 16w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-6-1-900x675.jpg 900w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/content-6-1-600x450.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\"  title=\"Les tendances du tourisme corporate en 2026\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6dcd27a elementor-section-stretched NotrePortfolio\u200b elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6dcd27a\" data-element_type=\"section\" id=\"NotrePortfolio\u200b\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/b-ltravel.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/AQOMRD0QJNUea-elvmC0LsfYkPq0XjwXmzXVJhAArPreETEvwM3uGHxWIXsZ2chnZ2Jr2r-vAyNU_ITVDpQGA65z.mp4&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-background-video-container elementor-hidden-mobile\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<video class=\"elementor-background-video-hosted\" autoplay muted playsinline loop><\/video>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d87ba45\" data-id=\"d87ba45\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d093678 elementor-widget elementor-widget-heading\" data-id=\"d093678\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Nos \u00e9v\u00e8nements  <\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-af4026b e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"af4026b\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-97222d3 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"97222d3\" data-element_type=\"section\" id=\"clients\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4e688ee\" data-id=\"4e688ee\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8f2ac95 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"8f2ac95\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-78cc3b8\" data-id=\"78cc3b8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-074019b elementor-widget elementor-widget-heading\" data-id=\"074019b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">T\u00e9moignages<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-99f099c elementor-widget elementor-widget-elementskit-testimonial\" data-id=\"99f099c\" data-element_type=\"widget\" data-widget_type=\"elementskit-testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"elementskit-testimonial-slider arrow_inside\" data-config=\"{&quot;rtl&quot;:false,&quot;arrows&quot;:false,&quot;dots&quot;:false,&quot;pauseOnHover&quot;:true,&quot;autoplay&quot;:true,&quot;speed&quot;:1000,&quot;slidesPerGroup&quot;:1,&quot;slidesPerView&quot;:3,&quot;loop&quot;:false,&quot;spaceBetween&quot;:15,&quot;breakpoints&quot;:{&quot;320&quot;:{&quot;slidesPerView&quot;:1,&quot;slidesPerGroup&quot;:1,&quot;spaceBetween&quot;:10},&quot;768&quot;:{&quot;slidesPerView&quot;:2,&quot;slidesPerGroup&quot;:1,&quot;spaceBetween&quot;:10},&quot;1024&quot;:{&quot;slidesPerView&quot;:3,&quot;slidesPerGroup&quot;:1,&quot;spaceBetween&quot;:15}}}\">\n\t<div class=\"ekit-main-swiper swiper\">\n\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t<div class=\"swiper-slide-inner\">\n\t\t\t\t\t<div class=\"elementskit-testimonial-inner elementor-repeater-item-cdd0ecb\" >\n\t\t\t\t\t\t<div class=\"elementskit-single-testimonial-slider   ekit_testimonial_style_2\">\n\t\t\t\t\t\t\t<div class=\"elementskit-commentor-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p> \u2018\u2019Organisation irr\u00e9prochable, \u00e9quipe \u00e0 l'\u00e9coute et tr\u00e8s r\u00e9active. Un vrai partenaire de confiance. \u2019\u2019\n<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementskit-border-hr\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementskit-profile-info\">\n\t\t\t\t\t\t\t\t\t<strong class=\"elementskit-author-name\">DIRECTEUR MARKETING <\/strong>\n\t\t\t\t\t\t\t\t\t<span class=\"elementskit-author-des\">Groupe International<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-watermark-icon\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-quote\"><\/i>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t<div class=\"swiper-slide-inner\">\n\t\t\t\t\t<div class=\"elementskit-testimonial-inner elementor-repeater-item-08b30a2\" >\n\t\t\t\t\t\t<div class=\"elementskit-single-testimonial-slider   ekit_testimonial_style_2\">\n\t\t\t\t\t\t\t<div class=\"elementskit-commentor-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>\u2018\u2019BLT a pris en charge notre congr\u00e8s international avec un niveau de service exceptionnel.\u2019\u2019<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementskit-border-hr\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementskit-profile-info\">\n\t\t\t\t\t\t\t\t\t<strong class=\"elementskit-author-name\">RESPONSABLE \u00c9V\u00c9NEMENTIEL <\/strong>\n\t\t\t\t\t\t\t\t\t<span class=\"elementskit-author-des\">Institution Publique<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-watermark-icon\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-quote\"><\/i>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t<div class=\"swiper-slide-inner\">\n\t\t\t\t\t<div class=\"elementskit-testimonial-inner elementor-repeater-item-823e683\" >\n\t\t\t\t\t\t<div class=\"elementskit-single-testimonial-slider   ekit_testimonial_style_2\">\n\t\t\t\t\t\t\t<div class=\"elementskit-commentor-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>\u2018\u2019Disponibilit\u00e9 24\/7 et suivi sur mesure. Je recommande vivement leurs services.\u2019\u2019\n<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementskit-border-hr\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementskit-profile-info\">\n\t\t\t\t\t\t\t\t\t<strong class=\"elementskit-author-name\">CEO<\/strong>\n\t\t\t\t\t\t\t\t\t<span class=\"elementskit-author-des\">Entreprise Priv\u00e9e<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-watermark-icon\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-quote\"><\/i>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t<div class=\"swiper-slide-inner\">\n\t\t\t\t\t<div class=\"elementskit-testimonial-inner elementor-repeater-item-5feab37\" >\n\t\t\t\t\t\t<div class=\"elementskit-single-testimonial-slider   ekit_testimonial_style_2\">\n\t\t\t\t\t\t\t<div class=\"elementskit-commentor-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>\u2018\u2019Voyage d'affaires parfaitement organis\u00e9, des prestations haut de gamme. Merci BLT !\u2019\u2019<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementskit-border-hr\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementskit-profile-info\">\n\t\t\t\t\t\t\t\t\t<strong class=\"elementskit-author-name\">Office Manager<\/strong>\n\t\t\t\t\t\t\t\t\t<span class=\"elementskit-author-des\">Entreprise Priv\u00e9e<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-watermark-icon\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-quote\"><\/i>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\t<\/div>\n<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1b56819 elementor-section-stretched partenaires elementor-section-full_width elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"1b56819\" data-element_type=\"section\" id=\"partenaires\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-701a672\" data-id=\"701a672\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a1ada8a elementor-widget elementor-widget-heading\" data-id=\"a1ada8a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Our partners<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8653dfa elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"8653dfa\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;5&quot;,&quot;slides_to_scroll&quot;:&quot;3&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;slides_to_show_tablet&quot;:&quot;3&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d\u2019images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 26\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/elementor\/thumbs\/content-5-1-rsr93mu3it34yoce31v9zwp88dhoq14i8r3lsb709o.jpg\" alt=\"Content 5 1 Rsr93mu3it34yoce31v9zwp88dhoq14i8r3lsb709o\"  title=\"Les tendances du tourisme corporate en 2026\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 26\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/elementor\/thumbs\/content-3-1-rsr93kyf550kbgf4e120ux6b1lqyamx1khsmtr9sm4.jpg\" alt=\"Content 3 1 Rsr93kyf550kbgf4e120ux6b1lqyamx1khsmtr9sm4\"  title=\"Les tendances du tourisme corporate en 2026\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 26\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/elementor\/thumbs\/content-6-1-rsr93oprwh5plw9ns2oj4w85f58f5fbyx0ekqv47x8.jpg\" alt=\"Content 6 1 Rsr93oprwh5plw9ns2oj4w85f58f5fbyx0ekqv47x8\"  title=\"Les tendances du tourisme corporate en 2026\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 26\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/elementor\/thumbs\/content-2-1-rsr93j2qrgxzo8hup08rpxnduu07v8pkw8hnv7ckyk.jpg\" alt=\"Content 2 1 Rsr93j2qrgxzo8hup08rpxnduu07v8pkw8hnv7ckyk\"  title=\"Les tendances du tourisme corporate en 2026\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 26\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/elementor\/thumbs\/content-5-1-rsr93mu3it34yoce31v9zwp88dhoq14i8r3lsb709o.jpg\" alt=\"Content 5 1 Rsr93mu3it34yoce31v9zwp88dhoq14i8r3lsb709o\"  title=\"Les tendances du tourisme corporate en 2026\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 26\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/elementor\/thumbs\/content-5-1-rsr93mu3it34yoce31v9zwp88dhoq14i8r3lsb709o.jpg\" alt=\"Content 5 1 Rsr93mu3it34yoce31v9zwp88dhoq14i8r3lsb709o\"  title=\"Les tendances du tourisme corporate en 2026\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 26\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/elementor\/thumbs\/content-3-1-rsr93kyf550kbgf4e120ux6b1lqyamx1khsmtr9sm4.jpg\" alt=\"Content 3 1 Rsr93kyf550kbgf4e120ux6b1lqyamx1khsmtr9sm4\"  title=\"Les tendances du tourisme corporate en 2026\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 26\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/elementor\/thumbs\/content-1-1-rsr93i4wkmwpcmj7uhu55fvx9g4unjluk3u6dxdz4s.jpg\" alt=\"Content 1 1 Rsr93i4wkmwpcmj7uhu55fvx9g4unjluk3u6dxdz4s\"  title=\"Les tendances du tourisme corporate en 2026\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 26\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/elementor\/thumbs\/content-6-1-rsr93oprwh5plw9ns2oj4w85f58f5fbyx0ekqv47x8.jpg\" alt=\"Content 6 1 Rsr93oprwh5plw9ns2oj4w85f58f5fbyx0ekqv47x8\"  title=\"Les tendances du tourisme corporate en 2026\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 26\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/elementor\/thumbs\/content-6-1-rsr93oprwh5plw9ns2oj4w85f58f5fbyx0ekqv47x8.jpg\" alt=\"Content 6 1 Rsr93oprwh5plw9ns2oj4w85f58f5fbyx0ekqv47x8\"  title=\"Les tendances du tourisme corporate en 2026\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 of 26\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/elementor\/thumbs\/content-6-1-rsr93oprwh5plw9ns2oj4w85f58f5fbyx0ekqv47x8.jpg\" alt=\"Content 6 1 Rsr93oprwh5plw9ns2oj4w85f58f5fbyx0ekqv47x8\"  title=\"Les tendances du tourisme corporate en 2026\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 of 26\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/elementor\/thumbs\/content-1-1-rsr93i4wkmwpcmj7uhu55fvx9g4unjluk3u6dxdz4s.jpg\" alt=\"Content 1 1 Rsr93i4wkmwpcmj7uhu55fvx9g4unjluk3u6dxdz4s\"  title=\"Les tendances du tourisme corporate en 2026\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 of 26\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/elementor\/thumbs\/content-6-1-rsr93oprwh5plw9ns2oj4w85f58f5fbyx0ekqv47x8.jpg\" alt=\"Content 6 1 Rsr93oprwh5plw9ns2oj4w85f58f5fbyx0ekqv47x8\"  title=\"Les tendances du tourisme corporate en 2026\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 of 26\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/elementor\/thumbs\/content-3-1-rsr93kyf550kbgf4e120ux6b1lqyamx1khsmtr9sm4.jpg\" alt=\"Content 3 1 Rsr93kyf550kbgf4e120ux6b1lqyamx1khsmtr9sm4\"  title=\"Les tendances du tourisme corporate en 2026\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 of 26\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/elementor\/thumbs\/content-1-1-rsr93i4wkmwpcmj7uhu55fvx9g4unjluk3u6dxdz4s.jpg\" alt=\"Content 1 1 Rsr93i4wkmwpcmj7uhu55fvx9g4unjluk3u6dxdz4s\"  title=\"Les tendances du tourisme corporate en 2026\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"16 of 26\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/elementor\/thumbs\/content-6-1-rsr93oprwh5plw9ns2oj4w85f58f5fbyx0ekqv47x8.jpg\" alt=\"Content 6 1 Rsr93oprwh5plw9ns2oj4w85f58f5fbyx0ekqv47x8\"  title=\"Les tendances du tourisme corporate en 2026\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"17 of 26\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/elementor\/thumbs\/content-2-1-rsr93j2qrgxzo8hup08rpxnduu07v8pkw8hnv7ckyk.jpg\" alt=\"Content 2 1 Rsr93j2qrgxzo8hup08rpxnduu07v8pkw8hnv7ckyk\"  title=\"Les tendances du tourisme corporate en 2026\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"18 of 26\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/elementor\/thumbs\/content-4-1-rsr93lw9bz1un2dr8jgnfexrmzmbic0rwmg4b18efw.jpg\" alt=\"Content 4 1 Rsr93lw9bz1un2dr8jgnfexrmzmbic0rwmg4b18efw\"  title=\"Les tendances du tourisme corporate en 2026\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"19 of 26\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/elementor\/thumbs\/content-2-1-rsr93j2qrgxzo8hup08rpxnduu07v8pkw8hnv7ckyk.jpg\" alt=\"Content 2 1 Rsr93j2qrgxzo8hup08rpxnduu07v8pkw8hnv7ckyk\"  title=\"Les tendances du tourisme corporate en 2026\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"20 of 26\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/elementor\/thumbs\/content-2-1-rsr93j2qrgxzo8hup08rpxnduu07v8pkw8hnv7ckyk.jpg\" alt=\"Content 2 1 Rsr93j2qrgxzo8hup08rpxnduu07v8pkw8hnv7ckyk\"  title=\"Les tendances du tourisme corporate en 2026\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"21 of 26\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/elementor\/thumbs\/content-5-1-rsr93mu3it34yoce31v9zwp88dhoq14i8r3lsb709o.jpg\" alt=\"Content 5 1 Rsr93mu3it34yoce31v9zwp88dhoq14i8r3lsb709o\"  title=\"Les tendances du tourisme corporate en 2026\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"22 of 26\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/elementor\/thumbs\/content-1-1-rsr93i4wkmwpcmj7uhu55fvx9g4unjluk3u6dxdz4s.jpg\" alt=\"Content 1 1 Rsr93i4wkmwpcmj7uhu55fvx9g4unjluk3u6dxdz4s\"  title=\"Les tendances du tourisme corporate en 2026\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"23 of 26\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/elementor\/thumbs\/content-2-1-rsr93j2qrgxzo8hup08rpxnduu07v8pkw8hnv7ckyk.jpg\" alt=\"Content 2 1 Rsr93j2qrgxzo8hup08rpxnduu07v8pkw8hnv7ckyk\"  title=\"Les tendances du tourisme corporate en 2026\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"24 of 26\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/elementor\/thumbs\/content-6-1-rsr93oprwh5plw9ns2oj4w85f58f5fbyx0ekqv47x8.jpg\" alt=\"Content 6 1 Rsr93oprwh5plw9ns2oj4w85f58f5fbyx0ekqv47x8\"  title=\"Les tendances du tourisme corporate en 2026\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"25 of 26\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/elementor\/thumbs\/content-1-1-rsr93i4wkmwpcmj7uhu55fvx9g4unjluk3u6dxdz4s.jpg\" alt=\"Content 1 1 Rsr93i4wkmwpcmj7uhu55fvx9g4unjluk3u6dxdz4s\"  title=\"Les tendances du tourisme corporate en 2026\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"26 of 26\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/elementor\/thumbs\/content-4-1-rsr93lw9bz1un2dr8jgnfexrmzmbic0rwmg4b18efw.jpg\" alt=\"Content 4 1 Rsr93lw9bz1un2dr8jgnfexrmzmbic0rwmg4b18efw\"  title=\"Les tendances du tourisme corporate en 2026\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d67e309 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"d67e309\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-92691a7\" data-id=\"92691a7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e5a4bdc elementor-widget elementor-widget-heading\" data-id=\"e5a4bdc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Blog \/ Actualit\u00e9s<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b21dbb elementor-widget elementor-widget-hfe-basic-posts\" data-id=\"5b21dbb\" data-element_type=\"widget\" data-widget_type=\"hfe-basic-posts.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"hfe-posts-grid\">\n\t\t\t<article class=\"hfe-post-card\">\n\t\t\t\t\t\t\t<div class=\"hfe-post-image\">\n\t\t\t\t\t<a href=\"https:\/\/b-ltravel.com\/en\/les-meilleures-destinations-business\/\" rel=\"bookmark\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/portfolio-1-2.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Les meilleures destinations business\" title=\"Les meilleures destinations business\" \/>\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"hfe-post-content\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"hfe-post-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/b-ltravel.com\/en\/les-meilleures-destinations-business\/\" rel=\"bookmark\">\n\t\t\t\t\t\t\tLes meilleures destinations business\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"hfe-post-meta\">\n\t\t\t\t\t\t<span class=\"hfe-post-date\">24 August 2026<\/span><span class=\"hfe-meta-separator\"> | <\/span><span class=\"hfe-post-author\">by admin<\/span>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"hfe-post-excerpt\">\n\t\t\t\t\t\tLes meilleures destinations business\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/b-ltravel.com\/en\/les-meilleures-destinations-business\/\" class=\"hfe-read-more\" rel=\"bookmark\">\n\t\t\t\t\t\tLire la suite \u2192\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"hfe-post-card\">\n\t\t\t\t\t\t\t<div class=\"hfe-post-image\">\n\t\t\t\t\t<a href=\"https:\/\/b-ltravel.com\/en\/conseils-pour-organiser-un-seminaire-reussi\/\" rel=\"bookmark\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/08\/ChatGPT-Image-1-sept.-2026-22_07_12-300x200.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Comment organiser un s\u00e9minaire r\u00e9ussi ? 10 conseils | BLT\" srcset=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/08\/ChatGPT-Image-1-sept.-2026-22_07_12-300x200.png 300w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/08\/ChatGPT-Image-1-sept.-2026-22_07_12-1024x683.png 1024w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/08\/ChatGPT-Image-1-sept.-2026-22_07_12-768x512.png 768w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/08\/ChatGPT-Image-1-sept.-2026-22_07_12-18x12.png 18w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/08\/ChatGPT-Image-1-sept.-2026-22_07_12-900x600.png 900w, https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/08\/ChatGPT-Image-1-sept.-2026-22_07_12.png 1536w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"Comment organiser un s\u00e9minaire r\u00e9ussi ? 10 conseils | BLT\" \/>\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"hfe-post-content\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"hfe-post-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/b-ltravel.com\/en\/conseils-pour-organiser-un-seminaire-reussi\/\" rel=\"bookmark\">\n\t\t\t\t\t\t\tComment organiser un s\u00e9minaire r\u00e9ussi ? 10 conseils | BLT\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"hfe-post-meta\">\n\t\t\t\t\t\t<span class=\"hfe-post-date\">24 August 2026<\/span><span class=\"hfe-meta-separator\"> | <\/span><span class=\"hfe-post-author\">by admin<\/span>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"hfe-post-excerpt\">\n\t\t\t\t\t\tConseils pour organiser un s\u00e9minaire r\u00e9ussi Conseils pour organiser un s\u00e9minaire r\u00e9ussi Organiser un s\u00e9minaire d\u2019entreprise est une excellente occasion...\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/b-ltravel.com\/en\/conseils-pour-organiser-un-seminaire-reussi\/\" class=\"hfe-read-more\" rel=\"bookmark\">\n\t\t\t\t\t\tLire la suite \u2192\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"hfe-post-card\">\n\t\t\t\t\t\t\t<div class=\"hfe-post-image\">\n\t\t\t\t\t<a href=\"https:\/\/b-ltravel.com\/en\/les-tendances-du-tourisme-corporate-en-2026\/\" rel=\"bookmark\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/b-ltravel.com\/wp-content\/uploads\/2026\/09\/portfolio-3-2.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Les tendances du tourisme corporate en 2026\" title=\"Les tendances du tourisme corporate en 2026\" \/>\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"hfe-post-content\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"hfe-post-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/b-ltravel.com\/en\/les-tendances-du-tourisme-corporate-en-2026\/\" rel=\"bookmark\">\n\t\t\t\t\t\t\tLes tendances du tourisme corporate en 2026\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"hfe-post-meta\">\n\t\t\t\t\t\t<span class=\"hfe-post-date\">24 August 2026<\/span><span class=\"hfe-meta-separator\"> | <\/span><span class=\"hfe-post-author\">by admin<\/span>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"hfe-post-excerpt\">\n\t\t\t\t\t\tLes tendances du tourisme corporate en 2026\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/b-ltravel.com\/en\/les-tendances-du-tourisme-corporate-en-2026\/\" class=\"hfe-read-more\" rel=\"bookmark\">\n\t\t\t\t\t\tLire la suite \u2192\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-0671bb0 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"0671bb0\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bbdf85d elementor-widget elementor-widget-heading\" data-id=\"bbdf85d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">contact<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-77f949c elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"77f949c\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d29ebca\" data-id=\"d29ebca\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-95a84c9 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"95a84c9\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3be174f\" data-id=\"3be174f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9491417 elementor-widget elementor-widget-google_maps\" data-id=\"9491417\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Business%20%26%20Leisure%20Travel&#038;t=m&#038;z=14&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Business &amp; Leisure Travel\"\n\t\t\t\t\taria-label=\"Business &amp; Leisure Travel\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-915ff45 elementor-position-left elementor-vertical-align-middle elementor-view-default elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"915ff45\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"huge huge-google-maps\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAdresses\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tOffice No. A-1-1 Dream Center building. Corner of Mohamed V Avenue and Khaireddine Pacha Avenue, Tunis, Tunisia\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ecca7d9 elementor-position-left elementor-vertical-align-middle elementor-view-default elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"ecca7d9\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tNumber\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t+216 25 555 529\n,\n+216 71 904 844\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c39e1f elementor-position-left elementor-vertical-align-middle elementor-view-default elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"6c39e1f\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-mail-bulk\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tEmail\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tdc@b-ltravel.com\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1acd14f\" data-id=\"1acd14f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-82936bd elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"82936bd\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-644dbff\" data-id=\"644dbff\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c1cfc84 elementor-widget elementor-widget-heading\" data-id=\"c1cfc84\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Contact form<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8faeee5 elementor-widget elementor-widget-shortcode\" data-id=\"8faeee5\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"wpforms-container\" id=\"wpforms-9481\"><form id=\"wpforms-form-9481\" class=\"wpforms-validate wpforms-form\" data-formid=\"9481\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/13137\" data-token=\"5eb60d444e2ac3ac3b249c3dc88dbb20\" data-token-time=\"1788353146\" data-trp-original-action=\"\/en\/wp-json\/wp\/v2\/pages\/13137\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-9481-field_2-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"2\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-9481-field_2\">Informations personnelles <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-9481-field_2\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][2][first]\" placeholder=\"First name \" required><label for=\"wpforms-9481-field_2\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-9481-field_2-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][2][last]\" placeholder=\"name\" required><label for=\"wpforms-9481-field_2-last\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">Last<\/label><\/div><\/div><\/div><div id=\"wpforms-9481-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-9481-field_1\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-9481-field_1\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][1]\" placeholder=\"Email\" spellcheck=\"false\" required><\/div><div id=\"wpforms-9481-field_0-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"0\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-9481-field_0\">Description<\/label><textarea id=\"wpforms-9481-field_0\" class=\"wpforms-field-large\" name=\"wpforms[fields][0]\" placeholder=\"Description\" ><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-field wpforms-field-hp\"><label for=\"wpforms-9481-field-hp\" class=\"wpforms-field-label\">Website<\/label><input type=\"text\" name=\"wpforms[hp]\" id=\"wpforms-9481-field-hp\" class=\"wpforms-field-medium\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"9481\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/b-ltravel.com\/en\/wp-json\/wp\/v2\/pages\/13137\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-9481\" class=\"wpforms-submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Send <\/button><\/div><input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form><\/div>  <!-- .wpforms-container --><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Business &amp; Leisure Travel Votre partenaire d\u2019excellence pour des exp\u00e9riences professionnelles et voyages d\u2019exception. D\u00e9couvrir nos services\/ Demande un devis Expertise &amp; confiance Plus de 13 ans d\u2019exp\u00e9rience au service de voyages fiables et ma\u00eetris\u00e9s. Excellence certifi\u00e9e IATA Une garantie de s\u00e9curit\u00e9, de conformit\u00e9 et de standards internationaux \u00e9lev\u00e9s. Assistance continue 7j\/7 Un accompagnement permanent pour une tranquillit\u00e9 totale \u00e0 chaque \u00e9tape. R\u00e9seau international premium Des partenaires s\u00e9lectionn\u00e9s dans le monde entier pour des exp\u00e9riences sur mesure. blt votre partenaire de succ\u00e8s Fond\u00e9e en 2013, BLT est une agence de voyages \u00e9v\u00e9nementielle de cat\u00e9gorie A. Nous proposons des prestations sur mesure : d\u00e9placements professionnels, voyages individuels, s\u00e9minaires, congr\u00e8s, team buildings, etc. Organisation d\u2019\u00e9v\u00e9nements &amp; MICE Conception et gestion compl\u00e8te de vos \u00e9v\u00e9nements professionnels : s\u00e9minaires, congr\u00e8s, conf\u00e9rences et programmes incentive. Une prise en charge globale pens\u00e9e pour garantir impact, fluidit\u00e9 et excellence op\u00e9rationnelle. CTA : Concevoir mon \u00e9v\u00e9nement sur mesure Solutions techniques &amp; interpr\u00e9tariat Mise \u00e0 disposition de mat\u00e9riel audiovisuel de pointe et services d\u2019interpr\u00e9tariat professionnels. Une expertise technique qui assure une communication fluide et une ex\u00e9cution sans faille de vos \u00e9v\u00e9nements internationaux. CTA : Garantir une ex\u00e9cution parfaite Team Building &amp; exp\u00e9riences d\u2019\u00e9quipe Cr\u00e9ation d\u2019exp\u00e9riences sur mesure pour renforcer la coh\u00e9sion et la performance des \u00e9quipes. Des activit\u00e9s innovantes, adapt\u00e9es \u00e0 vos objectifs RH et \u00e0 votre culture d\u2019entreprise. CTA : Cr\u00e9er une exp\u00e9rience d\u2019\u00e9quipe Voyage d\u2019affaires &amp; gestion des d\u00e9placements Gestion compl\u00e8te des voyages professionnels : planification, optimisation des co\u00fbts et assistance continue. Une solution pens\u00e9e pour la productivit\u00e9, la flexibilit\u00e9 et la tranquillit\u00e9 des voyageurs. CTA : Optimiser mes d\u00e9placements Billetterie &amp; mobilit\u00e9 internationale R\u00e9servation et \u00e9mission de billets d\u2019avion avec acc\u00e8s aux meilleures options et tarifs. Une gestion rapide et optimis\u00e9e pour tous vos d\u00e9placements nationaux et internationaux. CTA : Trouver mon meilleur itin\u00e9raire H\u00e9bergement &amp; transferts premium S\u00e9lection et r\u00e9servation d\u2019h\u00f4tels en Tunisie et \u00e0 l\u2019\u00e9tranger, accompagn\u00e9e de services de transport et transferts priv\u00e9s. Une exp\u00e9rience de mobilit\u00e9 fluide, confortable et hautement fiable. CTA : R\u00e9server une exp\u00e9rience fluide BLT Travel,\u00a0fond\u00e9e en 2013, est une agence de voyage premium sp\u00e9cialis\u00e9e dans les voyages d\u2019affaires et de loisirs sur mesure. Affili\u00e9e \u00e0 la FTAV et agr\u00e9\u00e9e IATA, l\u2019agence accompagne ses clients avec excellence, discr\u00e9tion et professionnalisme afin d\u2019offrir des exp\u00e9riences de voyage fluides, \u00e9l\u00e9gantes et parfaitement organis\u00e9es&#8230; En savoir plus Nos \u00e9v\u00e8nements Tout \u00e9v\u00e8nement 2 480914741_622592937394257_3435389903644411378_n WhatsApp Image 2025-05-10 at 13.02.45 (1) WhatsApp Image 2025-05-10 at 13.02.44 (12) WhatsApp Image 2025-05-10 at 13.02.44 (11) WhatsApp Image 2025-05-10 at 13.02.44 (10) WhatsApp Image 2025-05-10 at 13.02.43 (7) WhatsApp Image 2025-05-10 at 13.02.44 (16) WhatsApp Image 2025-05-10 at 13.02.44 (15) WhatsApp Image 2025-05-10 at 13.02.44 (14) WhatsApp Image 2025-05-10 at 13.02.42 (7) WhatsApp Image 2025-05-10 at 13.02.42 (3) WhatsApp Image 2025-05-10 at 13.02.42 (4) WhatsApp Image 2025-05-14 at 10.09.59 WhatsApp Image 2025-05-14 at 10.09.59 (1) WhatsApp Image 2025-05-14 at 10.09.59 (2) WhatsApp Image 2025-05-14 at 10.09.59 (3) photo-6 photo-206 photo-8 photo-62 solid-2 solid-4 WhatsApp Image 2025-05-19 at 11.03.56 WhatsApp Image 2025-05-19 at 11.03.54 (1) WhatsApp Image 2025-05-19 at 11.03.54 photo-2 WhatsApp Image 2025-05-19 at 11.03.53 WhatsApp Image 2025-05-19 at 10.30.18 JEUN\u2019ESS-49 (1) photo-18 photo-10 photo-78 photo-5 ATPC-1 Hivos_AfriFOODlinks-34 JEUN\u2019ESS-4 JEUNESS-51 T\u00e9moignages \u2018\u2019Organisation irr\u00e9prochable, \u00e9quipe \u00e0 l&rsquo;\u00e9coute et tr\u00e8s r\u00e9active. Un vrai partenaire de confiance. \u2019\u2019 DIRECTEUR MARKETING Groupe International \u2018\u2019BLT a pris en charge notre congr\u00e8s international avec un niveau de service exceptionnel.\u2019\u2019 RESPONSABLE \u00c9V\u00c9NEMENTIEL Institution Publique \u2018\u2019Disponibilit\u00e9 24\/7 et suivi sur mesure. Je recommande vivement leurs services.\u2019\u2019 CEO Entreprise Priv\u00e9e \u2018\u2019Voyage d&rsquo;affaires parfaitement organis\u00e9, des prestations haut de gamme. Merci BLT !\u2019\u2019 Office Manager Entreprise Priv\u00e9e Nos Partenaires Blog \/ Actualit\u00e9s Les meilleures destinations business 24 ao\u00fbt 2026 | par admin Les meilleures destinations business Lire la suite \u2192 Conseils pour organiser un s\u00e9minaire r\u00e9ussi 24 ao\u00fbt 2026 | par admin Conseils pour organiser un s\u00e9minaire r\u00e9ussi Lire la suite \u2192 Les tendances du tourisme corporate en 2026 24 ao\u00fbt 2026 | par admin Les tendances du tourisme corporate en 2026 Lire la suite \u2192 contact Adresses Bureau N\u00b0 A-1-1 Immeuble Dream Center. Angle avenue Mohamed V et avenue Khaireddine Pacha., Tunis, Tunisia Num\u00e9ro +216 25 555 529 , +216 71 904 844 Email dc@b-ltravel.com Formulaire de contact<\/p>","protected":false},"author":1,"featured_media":10589,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-13137","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/b-ltravel.com\/en\/wp-json\/wp\/v2\/pages\/13137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/b-ltravel.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/b-ltravel.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/b-ltravel.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/b-ltravel.com\/en\/wp-json\/wp\/v2\/comments?post=13137"}],"version-history":[{"count":37,"href":"https:\/\/b-ltravel.com\/en\/wp-json\/wp\/v2\/pages\/13137\/revisions"}],"predecessor-version":[{"id":13224,"href":"https:\/\/b-ltravel.com\/en\/wp-json\/wp\/v2\/pages\/13137\/revisions\/13224"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/b-ltravel.com\/en\/wp-json\/wp\/v2\/media\/10589"}],"wp:attachment":[{"href":"https:\/\/b-ltravel.com\/en\/wp-json\/wp\/v2\/media?parent=13137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}